{"id":109061,"date":"2026-02-03T16:31:07","date_gmt":"2026-02-03T16:31:07","guid":{"rendered":"https:\/\/www.primor.eu\/blog\/?p=109061"},"modified":"2026-02-03T16:31:21","modified_gmt":"2026-02-03T16:31:21","slug":"cuidar-piel-tratamiento-quimioterapia","status":"publish","type":"post","link":"https:\/\/www.primor.eu\/blog\/cuidar-piel-tratamiento-quimioterapia\/","title":{"rendered":"C\u00f3mo cuidar la piel durante un tratamiento de quimioterapia seg\u00fan los expertos"},"content":{"rendered":"\n<p><strong>Cuidar la piel <\/strong>durante la <strong><a href=\"https:\/\/www.primor.eu\/blog\/mejores-cremas-faciales-para-la-quimio\/\" data-type=\"link\" data-id=\"https:\/\/www.primor.eu\/blog\/mejores-cremas-faciales-para-la-quimio\/\">quimioterapia<\/a> <\/strong>es algo que no solo te har\u00e1 sentir mejor, sino que necesitar\u00e1s. Cuando se est\u00e1 recibiendo un tratamiento de quimioterapia la piel suele resentirse. Desde la <strong>sequedad extrema <\/strong>hasta algunas afecciones como pueden ser la <strong>dermatitis<\/strong>, hasta sarpullidos o reacciones a algunos productos. Es por eso que hay unas claves espec\u00edficas para cuidar la piel durante la quimioterapia. Te las contamos y te recomendamos algunos productos para ello.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">6 consejos para cuidar la piel durante la quimioterapia<\/h2>\n\n\n\n<p>Lo sabemos, una rutina beauty requiere de varios pasos y productos. Desde la limpieza hasta la hidrataci\u00f3n profunda o los tratamientos espec\u00edficos como pueden ser los indicados para pieles sensibles, acneicas o con otras afecciones como dermatitis o <strong>eccema<\/strong>. Especialmente cuidar la piel durante la quimioterapia requiere de unas claves espec\u00edficas. Son estas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Usa productos suaves o bio<\/strong>: siempre que puedas o hidratantes naturales sin qu\u00edmicos como los aceites vegetales. La piel los absorber\u00e1 bien porque durante la quimio tiende a resecarse demasiado.&nbsp;<\/li>\n\n\n\n<li><strong>Elige productos de farmacia o hipoalerg\u00e9nicos<\/strong>: como los de la Roche-Posay o Isdin. Porque suelen estar formulados con ingredientes respetuosos para afecciones o pieles extremadamente sensibles e incluso al\u00e9rgicas.<\/li>\n\n\n\n<li><strong>No exfolies tu piel<\/strong>: porque la sequedad durante el tratamiento de quimioterapia es extrema y puede descamarse. Elige limpiadores muy suaves, con la menor cantidad de qu\u00edmica posible.<\/li>\n\n\n\n<li><strong>Evita el agua caliente en tu piel<\/strong>: porque al estar muy sensible tambi\u00e9n puede verse afectada por las altas temperaturas. Es mejor que elijas ducharte con agua tibia incluso en invierno. Para lavar tu cutis lo mejor es el agua fr\u00eda.<\/li>\n\n\n\n<li><strong>Utiliza productos espec\u00edficos<\/strong>: hay algunos que ayudan espec\u00edficamente a paliar los efectos secundarios de la quimio y a cuidar la piel durante la quimioterapia.<\/li>\n\n\n\n<li><strong>Usa protector solar<\/strong>: porque durante el periodo de la quimio el sol afecta a tu piel mucho m\u00e1s.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Los mejores productos para cuidar tu piel durante la quimioterapia<\/h2>\n\n\n        <product-table class=\"pr-slider\">\r\n            <product-headers class=\"grid-table-rows\">\r\n                <div>Foto<\/div>\r\n                <div>Producto<\/div>\r\n                <div>Marca<\/div>\r\n                <div>Valoraciones<\/div>\r\n                <div>Precio<\/div>\r\n            <\/product-headers>\r\n\r\n            <product-list>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/avene-xeracalm-ad-balsamo-relipidizante-106590.html?#854=66337\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/2\/3282770154559_Eau_Thermale_Av_C3_A8ne_B_C3_A1lsamo_relipidizante_Xeracalm_A.D_0_90fb.jpg\" alt=\"Xeracalm AD B\u00e1lsamo Relipidizante\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #1 Top Ventas                            <\/div>\r\n\r\n                            <h2>\r\n                                Xeracalm AD B\u00e1lsamo Relipidizante                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/media\/catalog\/category\/Avene.png\" alt=\"Avene\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:98;\"><\/div>\r\n                                <b>4.9\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/biotherm-fluido-protector-diario-uv-spf50-aquascreen-127624.html\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/6\/3614274481549_1_5762.jpg\" alt=\"Fluido Protector Diario UV SPF50+ Aquascreen\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #2                            <\/div>\r\n\r\n                            <h2>\r\n                                Fluido Protector Diario UV SPF50+ Aquascreen                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/media\/catalog\/category\/biotherm.png\" alt=\"\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:100;\"><\/div>\r\n                                <b>5\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/la-roche-posay-lipikar-aceite-lavante-ap-106137.html?#854=66346\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/3\/3337875905466_1_f685.jpg\" alt=\"Lipikar Aceite Lavante AP+\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #3                            <\/div>\r\n\r\n                            <h2>\r\n                                Lipikar Aceite Lavante AP+                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/media\/catalog\/category\/la-roche-posay.png\" alt=\"La Roche-Posay\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:98;\"><\/div>\r\n                                <b>4.9\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                            <\/product-list>\r\n        <\/product-table>\r\n\r\n        \n\n\n\n<h3 class=\"wp-block-heading\">Xeracalm AD B\u00e1lsamo Relipidizante de Avene<\/h3>\n\n\n\n<p>Est\u00e1 indicado para las pieles con sequedad severa, con tendencia at\u00f3pica y con tendencia al picor. Para las pieles muy secas del beb\u00e9, del ni\u00f1o y del adulto. Prurito: sequedad intensa, prurito senil, psoriasis, tratamientos medicamentosos, variaciones hormonales (embarazo, menopausia), tratamientos oncol\u00f3gicos (radioterapia, quimioterapia). Dermatitis at\u00f3pica (como relevo de dermocorticoides).<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/avene-xeracalm-ad-balsamo-relipidizante-106590.html?#854=66337'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/2\/3282770154559_Eau_Thermale_Av_C3_A8ne_B_C3_A1lsamo_relipidizante_Xeracalm_A.D_0_90fb.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Fluido Protector Diario UV SPF50+ Aquascreen de Biotherm<\/h3>\n\n\n\n<p>Se absorbe f\u00e1cilmente y no deja residuos visibles. BIOTHERM ha creado este producto para quienes buscan un protector solar que se adapte a un estilo de vida activo. El Fluido Protector Diario UV SPF50+ Aquascreen est\u00e1 enriquecido con prote\u00ednas, vitaminas B3 y E, y Biotech Plankton\u2122, lo que contribuye a reforzar la barrera cut\u00e1nea y mejorar la hidrataci\u00f3n.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/biotherm-fluido-protector-diario-uv-spf50-aquascreen-127624.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/6\/3614274481549_1_5762.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Lipikar Aceite Lavante AP+ de La Roche-Posay<\/h3>\n\n\n\n<p>Limpiador nutritivo anti-irritaci\u00f3n para pieles at\u00f3picas con tendencia al eczema. Principales beneficios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Limpia suavemente la piel muy seca sensible sin frotar.<\/li>\n\n\n\n<li>Lo suficientemente suave como para utilizarlo en las zonas m\u00e1s sensibles del cuerpo; es adecuado para la limpieza de las zonas \u00edntimas, el cuero cabelludo de los beb\u00e9s y no pica los ojos.<\/li>\n\n\n\n<li>Apto para toda la familia, incluidos los reci\u00e9n nacidos.<\/li>\n\n\n\n<li>Ayuda a recuperar el confort y a reducir la irritaci\u00f3n.<\/li>\n\n\n\n<li>Hidrata en profundidad y reduce significativamente la sequedad de la piel hasta 24 horas.<\/li>\n<\/ul>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/la-roche-posay-lipikar-aceite-lavante-ap-106137.html?#854=66346'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/3\/3337875905466_1_f685.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Rosa Mosqueta Crema Hidratante de Babaria<\/h3>\n\n\n\n<p>La Crema Facial Hidratante 24h con Rosa Mosqueta de Babaria ofrece una hidrataci\u00f3n profunda y un efecto reafirmante, ideal para mantener la piel en su mejor estado. Formulada con Rosa Mosqueta, esta crema previene y corrige el envejecimiento cut\u00e1neo y los problemas relaciones con las radiaciones solares. Enriquecida con Carrageenan, proporciona un alto poder hidratante que dura 24 horas, alisando la piel en profundidad. Adem\u00e1s, cuenta con un factor de protecci\u00f3n solar SPG 15, protegiendo tu piel de los da\u00f1os del sol.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/babaria-rosa-mosqueta-crema-hidratante-14310.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/8\/4\/8410412056243_2cbd.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;109061&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;3&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Valora este art\u00edculo&quot;,&quot;legend&quot;:&quot;3\\\/5 - (2 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;C\u00f3mo cuidar la piel durante un tratamiento de quimioterapia seg\u00fan los expertos&quot;,&quot;width&quot;:&quot;84.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 84.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            3\/5 - (2 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuidar la piel durante la quimioterapia es algo que no solo te har\u00e1 sentir mejor, sino que necesitar\u00e1s. Cuando se est\u00e1 recibiendo un tratamiento de quimioterapia la piel suele resentirse. Desde la sequedad extrema hasta algunas afecciones como pueden ser la dermatitis, hasta sarpullidos o reacciones a algunos productos. Es por eso que hay unas [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":109062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"home-2","second_sidebar":"default-sidebar","sticky_sidebar":"0","share_position":"float","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"2","show_author_box":"0","show_post_related":"0","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[29],"tags":[],"class_list":["post-109061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmetica"],"_links":{"self":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/109061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/comments?post=109061"}],"version-history":[{"count":7,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/109061\/revisions"}],"predecessor-version":[{"id":138616,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/109061\/revisions\/138616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media\/109062"}],"wp:attachment":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media?parent=109061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/categories?post=109061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/tags?post=109061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}