{"id":107718,"date":"2024-07-05T13:47:42","date_gmt":"2024-07-05T13:47:42","guid":{"rendered":"https:\/\/www.primor.eu\/blog\/?p=107718"},"modified":"2024-06-27T11:34:50","modified_gmt":"2024-06-27T11:34:50","slug":"prohibicion-ue-acido-kojico","status":"publish","type":"post","link":"https:\/\/www.primor.eu\/blog\/prohibicion-ue-acido-kojico\/","title":{"rendered":"M\u00e1s all\u00e1 del retinol: la prohibici\u00f3n de la UE llega al \u00e1cido k\u00f3jico"},"content":{"rendered":"\n<p>Lo habr\u00e1s visto, o al menos te suena, as\u00ed que, s\u00ed, lo confirmamos: la <strong>Uni\u00f3n Europea (UE) ha limitado el uso del <\/strong><a href=\"https:\/\/www.primor.eu\/blog\/acido-kojico\/\"><strong>\u00e1cido k\u00f3jico<\/strong><\/a> en productos cosm\u00e9ticos, y no nos extra\u00f1a. Todas estamos enganchadas a TikTok, y aunque amamos los v\u00eddeos de tendencias y modas virales, a veces, es peligroso. La UE y los expertos estaban preocupados por el uso excesivo en concentraciones altas en productos de libre venta. Sobre todo, porque a pesar de ser un ingrediente muy beneficioso, no es para todo el mundo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 es el \u00e1cido k\u00f3jico<\/h2>\n\n\n\n<p>El <strong>\u00e1cido k\u00f3jico<\/strong> es un ingrediente com\u00fanmente utilizado en productos para el cuidado de la piel debido a sus propiedades para aclarar la piel y tratar la <strong>hiperpigmentaci\u00f3n<\/strong>. Sin embargo, varios estudios y evaluaciones han generado inquietudes sobre su potencial de causar efectos adversos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principales razones para limitar el \u00e1cido k\u00f3jico<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sensibilizaci\u00f3n y alergias<\/strong>. Puede causar sensibilizaci\u00f3n cut\u00e1nea con su uso continuo. \u00bfConsecuencias? Irritaci\u00f3n, enrojecimiento y dermatitis de contacto.<\/li>\n\n\n\n<li><strong>Genotoxicidad potencial<\/strong>. Algunos estudios que han levantado la alerta en la UE han sugerido que el \u00e1cido k\u00f3jico puede tener efectos genot\u00f3xicos, es decir, que podr\u00eda da\u00f1ar el material gen\u00e9tico de las c\u00e9lulas, lo que a largo plazo podr\u00eda aumentar el riesgo de c\u00e1ncer. Aunque estos estudios no son concluyentes, la posibilidad de riesgo ha llevado a las autoridades a ser cautelosas.<\/li>\n\n\n\n<li><strong>Concentraciones seguras<\/strong>. La evaluaci\u00f3n de seguridad llevada a cabo por el Comit\u00e9 Cient\u00edfico de Seguridad de los Consumidores (SCCS) de la Uni\u00f3n Europea ha concluido que el uso de \u00e1cido k\u00f3jico en concentraciones superiores al 1% en productos cosm\u00e9ticos no se considera seguro. Por ello, se ha limitado su concentraci\u00f3n m\u00e1xima permitida en productos cosm\u00e9ticos a este nivel.<\/li>\n\n\n\n<li><strong>\u2060Regulaci\u00f3n precautoria.<\/strong> En general, la UE aplica un principio de precauci\u00f3n cuando se trata de la seguridad de los ingredientes cosm\u00e9ticos. Si hay alguna evidencia que sugiera posibles riesgos para la salud humana, las autoridades pueden optar por limitar o prohibir el uso de ciertos ingredientes hasta que se demuestre de manera concluyente que son seguros.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo se ha limitado<\/h2>\n\n\n\n<p>En virtud de estas preocupaciones, la legislaci\u00f3n de la UE especifica que el \u00e1cido k\u00f3jico puede ser utilizado en productos cosm\u00e9ticos, pero \u00fanicamente hasta una <strong>concentraci\u00f3n m\u00e1xima del 1%.<\/strong> Esta regulaci\u00f3n est\u00e1 destinada a minimizar los riesgos potenciales asociados con su uso a largo plazo, al mismo tiempo que permite aprovechar sus beneficios en el cuidado de la piel.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;107718&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Valora este art\u00edculo&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;M\u00e1s all\u00e1 del retinol: la prohibici\u00f3n de la UE llega al \u00e1cido k\u00f3jico&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Valora este art\u00edculo<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo habr\u00e1s visto, o al menos te suena, as\u00ed que, s\u00ed, lo confirmamos: la Uni\u00f3n Europea (UE) ha limitado el uso del \u00e1cido k\u00f3jico en productos cosm\u00e9ticos, y no nos extra\u00f1a. Todas estamos enganchadas a TikTok, y aunque amamos los v\u00eddeos de tendencias y modas virales, a veces, es peligroso. La UE y los expertos [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":107838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"home-2","second_sidebar":"default-sidebar","sticky_sidebar":"0","share_position":"float","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"2","show_author_box":"0","show_post_related":"0","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[6299],"tags":[],"class_list":["post-107718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienestar"],"_links":{"self":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/107718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/comments?post=107718"}],"version-history":[{"count":1,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/107718\/revisions"}],"predecessor-version":[{"id":107863,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/107718\/revisions\/107863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media\/107838"}],"wp:attachment":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media?parent=107718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/categories?post=107718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/tags?post=107718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}