{"id":106768,"date":"2025-06-19T14:28:00","date_gmt":"2025-06-19T14:28:00","guid":{"rendered":"https:\/\/www.primor.eu\/blog\/?p=106768"},"modified":"2025-06-19T14:28:02","modified_gmt":"2025-06-19T14:28:02","slug":"mejores-productos-dermatologos-rebajas-de-verano","status":"publish","type":"post","link":"https:\/\/www.primor.eu\/blog\/mejores-productos-dermatologos-rebajas-de-verano\/","title":{"rendered":"Los mejores productos que recomiendan los dermat\u00f3logos con descuento en las rebajas de verano"},"content":{"rendered":"\n<p>\u00a1Ha llegado el verano! Y con \u00e9l la necesidad de sustituir nuestros <strong>b\u00e1sicos de belleza<\/strong> por otros m\u00e1s <strong>livianos<\/strong> que resulten fresquitos y que no saturen la piel. Gracias a las rebajas de verano de Primor, tenemos los <strong>mejores productos recomendados por dermat\u00f3logos para verano<\/strong> (aptos para todo tipo de pieles) que te vendr\u00e1n como anillo al dedo. \u00a1Prometido!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rebajas de verano de Primor: productos recomendados por derm\u00e1tologos<\/h2>\n\n\n        <product-table >\r\n            <product-headers class=\"grid-table-rows\">\r\n                <div>Foto<\/div>\r\n                <div>Producto<\/div>\r\n                <div>Marca<\/div>\r\n                <div>Valoraciones<\/div>\r\n                <div>Precio<\/div>\r\n            <\/product-headers>\r\n\r\n            <product-list>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/cerave-crema-reparadora-contorno-de-ojos-15828.html\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/10\/6XS11038_1_fe61.jpg\" alt=\"CeraVe Crema Reparadora Contorno de Ojos\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #1 Top Ventas                            <\/div>\r\n\r\n                            <h2>\r\n                                CeraVe Crema Reparadora Contorno de Ojos                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/09\/Cerave.jpg\" alt=\"85264\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:91.2;\"><\/div>\r\n                                <b>4.56\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/eucerin-hyaluron-filler-crema-antiarrugas-de-noche-81758.html\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2024\/06\/01_Product_997e.jpg\" alt=\"Eucerin Hyaluron-Filler Crema Antiarrugas de Noche\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #2                            <\/div>\r\n\r\n                            <h2>\r\n                                Eucerin Hyaluron-Filler Crema Antiarrugas de Noche                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/08\/Eucerin_logo.svg_1.png\" alt=\"84289\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:91.2;\"><\/div>\r\n                                <b>4.56\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/vichy-liftactiv-supreme-anti-arrugas-piel-normal-mixta-14380.html\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2024\/01\/6XS06047_1_4fa2.jpg\" alt=\"Vichy Liftactiv Supreme Anti Arrugas Piel Normal Mixta\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #3                            <\/div>\r\n\r\n                            <h2>\r\n                                Vichy Liftactiv Supreme Anti Arrugas Piel Normal Mixta                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/08\/vichy.png\" alt=\"84283\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:89;\"><\/div>\r\n                                <b>4.45\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                                    <a href=\"https:\/\/www.primor.eu\/es_es\/lancaster-sun-beauty-protector-solar-spf50-55104.html\" class=\"product-item grid-table-rows\" target=\"_blank\">\r\n                        <div>\r\n                            <img decoding=\"async\" class=\"product-img\" width=\"80px\" height=\"80px\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/09\/0TS02834_1_548f.jpg\" alt=\"Lancaster Sun Beauty Protector Solar SPF50\">\r\n                        <\/div>\r\n\r\n                        <!-- Contenido de producto  -->\r\n                        <div>\r\n                            <div class=\"product-position\">\r\n                                #4                            <\/div>\r\n\r\n                            <h2>\r\n                                Lancaster Sun Beauty Protector Solar SPF50                            <\/h2>\r\n                        <\/div>\r\n\r\n                        <!-- Imagen y\/o nombre de la marca -->\r\n                        <div>\r\n                                                            <img decoding=\"async\" width=\"70\" src=\"https:\/\/www.primor.eu\/blog\/wp-content\/uploads\/2023\/07\/lancaster.png\" alt=\"83115\">\r\n                                                    <\/div>\r\n\r\n                        <!-- Puntuaci\u00f3n del producto  -->\r\n                        <div class=\"rating\">\r\n                                                            <div class=\"rate\" style=\"--p:82.8;\"><\/div>\r\n                                <b>4.14\/5<\/b>\r\n                                <div class=\"rate-stars\">\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                            <div\r\n                                            class=\"rate-star  \">\r\n                                        <\/div>\r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n\r\n                        <!-- Bot\u00f3n de producto  -->\r\n                        <div>\r\n                            <span class=\"price-claim\">\r\n                                VER PRECIO                            <\/span>\r\n                        <\/div>\r\n                    <\/a>\r\n                            <\/product-list>\r\n        <\/product-table>\r\n\r\n        \n\n\n\n<h3 class=\"wp-block-heading\">Crema para ojos de Cerave<\/h3>\n\n\n\n<p>Reduce la apariencia de bolsas y arrugas para lograr una piel m\u00e1s luminosa y de aspecto m\u00e1s suave. Est\u00e1 testada al 100% por oftalm\u00f3logos, lo que garantiza su uso cerca de los ojos sin miedo a que se den alergias cut\u00e1neas. Adem\u00e1s, su f\u00f3rmula no contiene perfumes, no es nada grasa ni aceitosa y puede usarse en cualquier tipo de piel, tambi\u00e9n en las m\u00e1s sensibles.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/cerave-crema-reparadora-contorno-de-ojos-15828.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/3\/3337875597272_ae79.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Hyaluron Filler Crema Antiarrugas de Noche de Eucerin&nbsp;<\/h3>\n\n\n\n<p>La crema de arrugas de Eucerin es una crema de noche que act\u00faa sobre las arrugas mientras dormimos. Es una de las m\u00e1s recomendadas por los expertos y no es para menos, ya que reactiva en un 256% la producci\u00f3n de \u00c1cido Hialur\u00f3nico natural de la piel lo que hace que las arrugas se rellenen desde el interior. Los resultados son visibles de forma pr\u00e1cticamente instant\u00e1nea y est\u00e1 recomendada para pieles de entre 35 y 55 a\u00f1os.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/eucerin-hyaluron-filler-crema-antiarrugas-de-noche-106560.html?#863=67139'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/0\/1\/01_Product_d9c8.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Liftactiv Supreme Anti Arrugas Piel Normal Mixta de Vichy<\/h3>\n\n\n\n<p>La crema antiarrugas de Vichy se centra en 3 resultados principales: acci\u00f3n durante todo el d\u00eda con efecto reafirmantes, correcci\u00f3n de arrugas y firmeza. Gracias a sus ingredientes como son la cafe\u00edna, Ramnose, Neohesperidine y la Adenosina, ayudan a eliminar las arrugas, la cara efecto cansada, a la vez que act\u00faan como antioxidantes, calmantes e hidratantes con la piel. Consigue una piel visiblemente m\u00e1s firme y el\u00e1stica a partir del primer mes de uso.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/vichy-liftactiv-supreme-anti-arrugas-piel-normal-mixta-14380.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/3\/3\/3337871328795_1_b445.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Sun Beauty Loci\u00f3n Bronceadora de Lancaster<\/h3>\n\n\n\n<p>Este protector de Lancaster protege tu piel de los rayos UVA, UVB, luz visible e infrarrojos gracias a su tecnolog\u00eda Full Light, su fuerte acci\u00f3n incisiva y su alto factor de protecci\u00f3n SPF +50. Su textura fluida proporciona un bronceado gradual y natural con un acabado de terciopelo.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/lancaster-sun-beauty-protector-solar-spf50-55104.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/0\/T\/0TS02834_1_548f.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">Dermabsolu Rejuvenecedor de Av\u00e8ne<\/h3>\n\n\n\n<p>DermAbsolu de Av\u00e8ne redensifica, redefine y revitaliza la piel, gracias a sus componentes esenciales: polifenoles de vainilla, Sytenol y Glycoleol. La asociaci\u00f3n de estas sustancias estimula la s\u00edntesis de \u00e1cido hialur\u00f3nico y col\u00e1geno, fundamentales para la elasticidad y firmeza de los tejidos, y aporta nutrici\u00f3n y confort a la piel.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/avene-dermabsolu-contorno-de-ojos-rejuvenecedor-15558.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/6\/X\/6XS10614_1_e02f.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n\n<h3 class=\"wp-block-heading\">360\u00ba Gel Fotoprotector Water SPF50+ de Heliocare<\/h3>\n\n\n\n<p>Con Fernblock\u00ae+, filtros espec\u00edficos y activos reparadores y antioxidantes, este fotoprotector protege frente a las 4 radiaciones (UVB, UVA, Visible e Infrarrojo), neutraliza y repara el da\u00f1o solar. Su f\u00f3rmula acuosa, ultraligera y no comedog\u00e9nica se absorbe r\u00e1pidamente dejando la piel hidratada y manteniendo su confort durante la exposici\u00f3n solar. Adem\u00e1s, tambi\u00e9n cuenta con un sistema hidratante de liberaci\u00f3n prolongada que permite mantener la piel hidratada desde la aplicaci\u00f3n y a lo largo del tiempo.<\/p>\n\n\n    <a class='product' target='_blank' href='https:\/\/www.primor.eu\/es_es\/cantabria-labs-heliocare-360-gel-fotoprotector-water-spf-50-54913.html'>\r\n        <img loading='async' src='https:\/\/cdn2.primor.eu\/media\/catalog\/product\/cache\/8d3aba296f7a18b5251ee30fa5db42b2\/8\/4\/8470001930156__1__85ac.jpg' alt='COMPRAR AHORA'>\r\n            <div class=\"claim\">\r\n                COMPRAR AHORA            <\/div>\r\n        <\/a>\r\n    \n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;106768&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Valora este art\u00edculo&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Los mejores productos que recomiendan los dermat\u00f3logos con descuento en las rebajas de verano&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Valora este art\u00edculo<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ha llegado el verano! Y con \u00e9l la necesidad de sustituir nuestros b\u00e1sicos de belleza por otros m\u00e1s livianos que resulten fresquitos y que no saturen la piel. Gracias a las rebajas de verano de Primor, tenemos los mejores productos recomendados por dermat\u00f3logos para verano (aptos para todo tipo de pieles) que te vendr\u00e1n como [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":106804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"home-2","second_sidebar":"default-sidebar","sticky_sidebar":"0","share_position":"float","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"0","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"0","show_prev_next_post":"0","show_popup_post":"0","number_popup_post":"2","show_author_box":"0","show_post_related":"0","show_inline_post_related":"1"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[29],"tags":[],"class_list":["post-106768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosmetica"],"_links":{"self":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/106768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/comments?post=106768"}],"version-history":[{"count":2,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/106768\/revisions"}],"predecessor-version":[{"id":127770,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/posts\/106768\/revisions\/127770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media\/106804"}],"wp:attachment":[{"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/media?parent=106768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/categories?post=106768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primor.eu\/blog\/wp-json\/wp\/v2\/tags?post=106768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}